{"id":104414,"date":"2025-01-27T12:25:00","date_gmt":"2025-01-27T11:25:00","guid":{"rendered":"https:\/\/musikabulegoa.eus\/hub\/?p=104414"},"modified":"2025-01-27T12:25:00","modified_gmt":"2025-01-27T11:25:00","slug":"abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4","status":"publish","type":"post","link":"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/","title":{"rendered":"Abierto el plazo para presentar propuestas ante programadores\/as de Sarea"},"content":{"rendered":"<p>Musika Bulegoa ha abierto el plazo de presentaci\u00f3n de propuestas para la 8\u00aa edici\u00f3n del encuentro entre profesionales del sector musical y programadores\/as de la Red Vasca de Teatros SAREA.<\/p>\n<p>Las propuestas se podr\u00e1n presentar <strong>hasta las 23:59 horas del 17 de febrero <\/strong>y deber\u00e1n enviarse a trav\u00e9s de este <a href=\"https:\/\/forms.gle\/Jwg8tatMUbyEEx6T9\"><strong><u>formulario<\/u><\/strong><\/a>.<\/p>\n<p>Aqu\u00ed puedes consultar <a href=\"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2025\/01\/2025_CONVOCATORIA_SAREA.pdf\">las bases<\/a>\u00a0de esta\u00a0convocatoria.<\/p>\n<p>Los trabajos\/espect\u00e1culos musicales seleccionados se comunicar\u00e1n a principios de marzo y recibir\u00e1n una ayuda econ\u00f3mica de 120\u20ac.<\/p>\n<p><strong>El encuentro se celebrar\u00e1 el 2 de abril<\/strong> en el Teatro Arriola de Elorrio (Bizkaia) en horario de ma\u00f1ana. La jornada estar\u00e1 dividida en dos partes. En la primera, los grupos presentar\u00e1n sus \u00faltimos trabajos en directo. Tras las presentaciones, habr\u00e1 una sesi\u00f3n de networking.<br \/>\n<iframe  id=\"_ytid_67035\"  width=\"800\" height=\"450\"  data-origwidth=\"800\" data-origheight=\"450\" src=\"https:\/\/www.youtube.com\/embed\/hOYWQHpQ9bA?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;modestbranding=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Musika Bulegoa ha abierto el plazo de presentaci\u00f3n de propuestas para la 8\u00aa edici\u00f3n del encuentro entre profesionales del sector [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":104419,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1,480],"tags":[318],"class_list":["post-104414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-convocatoria","tag-abierta"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Abierto el plazo para presentar propuestas ante programadores\/as de Sarea - Musika Bulegoa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abierto el plazo para presentar propuestas ante programadores\/as de Sarea - Musika Bulegoa\" \/>\n<meta property=\"og:description\" content=\"Musika Bulegoa ha abierto el plazo de presentaci\u00f3n de propuestas para la 8\u00aa edici\u00f3n del encuentro entre profesionales del sector [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Musika Bulegoa\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-27T11:25:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2025\/01\/MB-SAREA-TOPAKEA075-1200x800.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MusikaBulegoa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"MusikaBulegoa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/\",\"url\":\"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/\",\"name\":\"Abierto el plazo para presentar propuestas ante programadores\/as de Sarea - Musika Bulegoa\",\"isPartOf\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2025\/01\/MB-SAREA-TOPAKEA075.jpg\",\"datePublished\":\"2025-01-27T11:25:00+00:00\",\"dateModified\":\"2025-01-27T11:25:00+00:00\",\"author\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/en\/#\/schema\/person\/62018fc25a2175efcf1a75cb8eac0b0f\"},\"breadcrumb\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/#primaryimage\",\"url\":\"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2025\/01\/MB-SAREA-TOPAKEA075.jpg\",\"contentUrl\":\"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2025\/01\/MB-SAREA-TOPAKEA075.jpg\",\"width\":2362,\"height\":1575},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/musikabulegoa.eus\/hub\/en\/hub\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abierto el plazo para presentar propuestas ante programadores\/as de Sarea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/en\/#website\",\"url\":\"https:\/\/musikabulegoa.eus\/hub\/en\/\",\"name\":\"Musika Bulegoa\",\"description\":\"La Oficina de la M\u00fasica de Euskal Herria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/musikabulegoa.eus\/hub\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/en\/#\/schema\/person\/62018fc25a2175efcf1a75cb8eac0b0f\",\"name\":\"MusikaBulegoa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/127e5bff70608c38f998a3db1a101158?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/127e5bff70608c38f998a3db1a101158?s=96&d=blank&r=g\",\"caption\":\"MusikaBulegoa\"},\"url\":\"https:\/\/musikabulegoa.eus\/hub\/en\/author\/musikabulegoa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abierto el plazo para presentar propuestas ante programadores\/as de Sarea - Musika Bulegoa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/","og_locale":"en_US","og_type":"article","og_title":"Abierto el plazo para presentar propuestas ante programadores\/as de Sarea - Musika Bulegoa","og_description":"Musika Bulegoa ha abierto el plazo de presentaci\u00f3n de propuestas para la 8\u00aa edici\u00f3n del encuentro entre profesionales del sector [&hellip;]","og_url":"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/","og_site_name":"Musika Bulegoa","article_published_time":"2025-01-27T11:25:00+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2025\/01\/MB-SAREA-TOPAKEA075-1200x800.jpg","type":"image\/jpeg"}],"author":"MusikaBulegoa","twitter_card":"summary_large_image","twitter_misc":{"Written by":"MusikaBulegoa","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/","url":"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/","name":"Abierto el plazo para presentar propuestas ante programadores\/as de Sarea - Musika Bulegoa","isPartOf":{"@id":"https:\/\/musikabulegoa.eus\/hub\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/#primaryimage"},"image":{"@id":"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/#primaryimage"},"thumbnailUrl":"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2025\/01\/MB-SAREA-TOPAKEA075.jpg","datePublished":"2025-01-27T11:25:00+00:00","dateModified":"2025-01-27T11:25:00+00:00","author":{"@id":"https:\/\/musikabulegoa.eus\/hub\/en\/#\/schema\/person\/62018fc25a2175efcf1a75cb8eac0b0f"},"breadcrumb":{"@id":"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/#primaryimage","url":"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2025\/01\/MB-SAREA-TOPAKEA075.jpg","contentUrl":"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2025\/01\/MB-SAREA-TOPAKEA075.jpg","width":2362,"height":1575},{"@type":"BreadcrumbList","@id":"https:\/\/musikabulegoa.eus\/hub\/en\/abierto-el-plazo-para-presentar-propuestas-ante-programadores-as-de-sarea-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musikabulegoa.eus\/hub\/en\/hub\/"},{"@type":"ListItem","position":2,"name":"Abierto el plazo para presentar propuestas ante programadores\/as de Sarea"}]},{"@type":"WebSite","@id":"https:\/\/musikabulegoa.eus\/hub\/en\/#website","url":"https:\/\/musikabulegoa.eus\/hub\/en\/","name":"Musika Bulegoa","description":"La Oficina de la M\u00fasica de Euskal Herria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musikabulegoa.eus\/hub\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/musikabulegoa.eus\/hub\/en\/#\/schema\/person\/62018fc25a2175efcf1a75cb8eac0b0f","name":"MusikaBulegoa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/musikabulegoa.eus\/hub\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/127e5bff70608c38f998a3db1a101158?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/127e5bff70608c38f998a3db1a101158?s=96&d=blank&r=g","caption":"MusikaBulegoa"},"url":"https:\/\/musikabulegoa.eus\/hub\/en\/author\/musikabulegoa\/"}]}},"_links":{"self":[{"href":"https:\/\/musikabulegoa.eus\/hub\/en\/wp-json\/wp\/v2\/posts\/104414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musikabulegoa.eus\/hub\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/musikabulegoa.eus\/hub\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/en\/wp-json\/wp\/v2\/comments?post=104414"}],"version-history":[{"count":4,"href":"https:\/\/musikabulegoa.eus\/hub\/en\/wp-json\/wp\/v2\/posts\/104414\/revisions"}],"predecessor-version":[{"id":104426,"href":"https:\/\/musikabulegoa.eus\/hub\/en\/wp-json\/wp\/v2\/posts\/104414\/revisions\/104426"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/en\/wp-json\/wp\/v2\/media\/104419"}],"wp:attachment":[{"href":"https:\/\/musikabulegoa.eus\/hub\/en\/wp-json\/wp\/v2\/media?parent=104414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/en\/wp-json\/wp\/v2\/categories?post=104414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/en\/wp-json\/wp\/v2\/tags?post=104414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}