{"id":101736,"date":"2023-11-25T18:48:30","date_gmt":"2023-11-25T17:48:30","guid":{"rendered":"https:\/\/musikabulegoa.eus\/hub\/?p=101736"},"modified":"2023-11-28T18:48:45","modified_gmt":"2023-11-28T17:48:45","slug":"tres-grupos-vascos-en-la-iscm-de-sudafrica","status":"publish","type":"post","link":"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/","title":{"rendered":"Tres grupos vascos en la ISCM de Sud\u00e1frica"},"content":{"rendered":"<p>Desde el <strong>24 de noviembre al 4 de diciembre<\/strong>, las ciudades sudafricanas de Johannesburgo y Ciudad del Cabo acoger\u00e1n un evento hist\u00f3rico para la m\u00fasica contempor\u00e1nea: la celebraci\u00f3n del <strong>centenario de la ISCM<\/strong> (International Society for Contemporary Music), con un gran festival que recorrer\u00e1 la larga historia de esta asociaci\u00f3n de \u00e1mbito mundial que fue creada en Salzburgo y celebr\u00f3 su primer festival en Londres en 1923. Esta ser\u00e1, adem\u00e1s, la primera vez que el festival anual de la ISCM, conocido como World New Music Days, se celebre en el continente africano, una decisi\u00f3n que fue tomada deliberadamente por la organizaci\u00f3n como un gesto y una reflexi\u00f3n sobre su propia historia y retos futuros al alcanzar la simb\u00f3lica cifra de 100 a\u00f1os.<\/p>\n<p>A lo largo de diez d\u00edas, las dos ciudades sud\u00e1fricanas acoger\u00e1n a compositores y destacados int\u00e9rpretes de m\u00fasica contempor\u00e1nea llegados de todo el mundo, que a lo largo de casi 30 conciertos dar\u00e1n una muestra de la nueva creaci\u00f3n actual, del repertorio hist\u00f3rico de la ISCM, y de la m\u00fasica cl\u00e1sica-contempor\u00e1nea africana, gran desconocida en todo el mundo y que tendr\u00e1 una presencia muy destacada en la programaci\u00f3n. La direcci\u00f3n art\u00edstica del festival ha estado en manos de <strong>Lukas Ligeti<\/strong>, compositor y percusionista, hijo del legendario Gy\u00f6rgy Ligeti, uno de los compositores m\u00e1s importantes del siglo XX (su m\u00fasica se puede escuchar, por ejemplo, en las bandas sonoras de <em>El resplandor<\/em> o <em>2001 <\/em>de Stanley Kubrick).<\/p>\n<p><strong>Tres grupos vascos<\/strong> se sumar\u00e1n a la programaci\u00f3n del festival sudafricano de la mano de Musika Bulegoa, que desde 2016 es miembro de la ISCM y acude junto con Musikagileak (Asociaci\u00f3n Vasco-Navarra de Compositores) a este festival anual itinerante (las \u00faltimas ediciones se han celebrado en Nueva Zelanda, Estonia, China y Canad\u00e1). Los tres grupos son el <strong>Tr\u00edo Akartia<\/strong>, el <strong>D\u00fao Casado-Croccolino<\/strong> y <strong>Oreka TX<\/strong>. Los primeros en participar ser\u00e1n el d\u00fao formado por el flautista <strong>Roberto Casado <\/strong>y la pianista<strong> Francesca Croccolino<\/strong>, que actuar\u00e1n en el auditorio de la Universidad de Johannesburgo el lunes 27 de noviembre, con un programa \u00edntegramente dedicado a compositores africanos como Justinian Tamusuza (Uganda), Fred Onovwerosuoke (Nigeria), Bongani Ndodana-Breen (Sud\u00e1frica) o J.H. Kwabena Nketia (Ghana). Tras este recital del d\u00fao en solitario, el flautista Roberto Casado participar\u00e1 en otros conciertos del festival tanto en Johannesburgo como en Ciudad del Cabo, colaborando con m\u00fasicos procedentes de todo el mundo en diversos grupos creados <em>ex profeso<\/em> para el festival.<\/p>\n<p>El <strong>Tr\u00edo Akartia<\/strong>, con sede en Vitoria-Gasteiz, est\u00e1 formado por la soprano Stefanie Knorr, la acordeonista Naiara de la Puente y el saxofonista I\u00f1igo Setuain. Los tres j\u00f3venes m\u00fasicos actuar\u00e1n, tanto en tr\u00edo, junto a otros m\u00fasicos o en solitario, en diversos conciertos que tendr\u00e1n lugar a lo largo y ancho de Ciudad del Cabo entre el 1 y el 3 de diciembre, en escenarios como la Youngblood Gallery, la Norval Foundation o el Ian Burgess-Simpson Studio.<\/p>\n<p>Por \u00faltimo, y por deseo expreso de Lukas Ligeti, viajar\u00e1 hasta Sud\u00e1frica el d\u00fao de txalapartaris <strong>Oreka TX<\/strong>, formado por Mikel Ugarte y Harkaitz Mart\u00ednez de San Vicente. Ofrecer\u00e1n una doble actuaci\u00f3n el 2 de diciembre en Ciudad del Cabo: a las 12:00, en el espacio al aire libre del Victoria &amp; Albert Waterfront, ofrecer\u00e1n un concierto de txalaparta mostrando las posibilidades de este instrumento paradigm\u00e1tico del folclore vasco; y, por la tarde, a las 19:30 en la Norval Foundation, compartir\u00e1n escenario con otros int\u00e9rpretes de m\u00fasicas de ra\u00edz: el mexicano Ernesto Mart\u00ednez y los ugandeses Bisaso Albert Ssempeke y James Isarbiye, mostrando los frutos del trabajo conjunto de creaci\u00f3n que vendr\u00e1n realizando desde unos d\u00edas antes.<\/p>\n<p>Junto a la presencia de estos 7 int\u00e9rpretes vascos, tambi\u00e9n sonar\u00e1 en Sud\u00e1frica la m\u00fasica vasca actual. La obra vasca seleccionada en la convocatoria oficial de la ISCM 2023 ha sido <em>Larrazpileko jentilen trikuharritik<\/em> de <strong>Teresa Catal\u00e1n<\/strong>, una partitura estrenada en 2019 en la Quincena Musical de Donostia y que ver\u00e1 su presentaci\u00f3n internacional el 1 de diciembre en la Youngblood Gallery de Ciudad del Cabo, de manos del violinista David Bester, el violonchelista Aristide du Plessis y la pianista Nina Schumann. Adem\u00e1s de la obra de Catal\u00e1n, durante las intervenciones del D\u00fao Casado-Croccolino y del Tr\u00edo Akartia, y por supuesto de Oreka TX, sonar\u00e1n tambi\u00e9n varias p\u00e1ginas de m\u00fasica vasca.<\/p>\n<p>Junto con esta extensa representaci\u00f3n de m\u00fasicos vascos, Musika Bulegoa viajar\u00e1 a Sud\u00e1frica para participar en la Asamblea General de la ISCM, que se celebra durante 4 d\u00edas en paralelo al festival y en la que se deciden las l\u00edneas de actuaci\u00f3n que esta asociaci\u00f3n en defensa de la m\u00fasica contempor\u00e1nea seguir\u00e1 en los pr\u00f3ximos a\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el 24 de noviembre al 4 de diciembre, las ciudades sudafricanas de Johannesburgo y Ciudad del Cabo acoger\u00e1n un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":101737,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[501],"tags":[],"class_list":["post-101736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mb-internacionalizacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tres grupos vascos en la ISCM de Sud\u00e1frica - Musika Bulegoa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tres grupos vascos en la ISCM de Sud\u00e1frica - Musika Bulegoa\" \/>\n<meta property=\"og:description\" content=\"Desde el 24 de noviembre al 4 de diciembre, las ciudades sudafricanas de Johannesburgo y Ciudad del Cabo acoger\u00e1n un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/\" \/>\n<meta property=\"og:site_name\" content=\"Musika Bulegoa\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-25T17:48:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T17:48:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2023\/11\/Festival-Banner.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"451\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"nu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/\",\"url\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/\",\"name\":\"Tres grupos vascos en la ISCM de Sud\u00e1frica - Musika Bulegoa\",\"isPartOf\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2023\/11\/Festival-Banner.png\",\"datePublished\":\"2023-11-25T17:48:30+00:00\",\"dateModified\":\"2023-11-28T17:48:45+00:00\",\"author\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/#\/schema\/person\/481aba636998127bf1b06f1f70534c08\"},\"breadcrumb\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/#primaryimage\",\"url\":\"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2023\/11\/Festival-Banner.png\",\"contentUrl\":\"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2023\/11\/Festival-Banner.png\",\"width\":800,\"height\":451},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/hub\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tres grupos vascos en la ISCM de Sud\u00e1frica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/#website\",\"url\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/\",\"name\":\"Musika Bulegoa\",\"description\":\"La Oficina de la M\u00fasica de Euskal Herria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/#\/schema\/person\/481aba636998127bf1b06f1f70534c08\",\"name\":\"nu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/35c862e58dd566edb3ea4c54e317aeec?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/35c862e58dd566edb3ea4c54e317aeec?s=96&d=blank&r=g\",\"caption\":\"nu\"},\"url\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/author\/pedrositio-nu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tres grupos vascos en la ISCM de Sud\u00e1frica - Musika Bulegoa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/","og_locale":"fr_FR","og_type":"article","og_title":"Tres grupos vascos en la ISCM de Sud\u00e1frica - Musika Bulegoa","og_description":"Desde el 24 de noviembre al 4 de diciembre, las ciudades sudafricanas de Johannesburgo y Ciudad del Cabo acoger\u00e1n un [&hellip;]","og_url":"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/","og_site_name":"Musika Bulegoa","article_published_time":"2023-11-25T17:48:30+00:00","article_modified_time":"2023-11-28T17:48:45+00:00","og_image":[{"width":800,"height":451,"url":"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2023\/11\/Festival-Banner.png","type":"image\/png"}],"author":"nu","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"nu","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/","url":"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/","name":"Tres grupos vascos en la ISCM de Sud\u00e1frica - Musika Bulegoa","isPartOf":{"@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/#primaryimage"},"image":{"@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/#primaryimage"},"thumbnailUrl":"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2023\/11\/Festival-Banner.png","datePublished":"2023-11-25T17:48:30+00:00","dateModified":"2023-11-28T17:48:45+00:00","author":{"@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/#\/schema\/person\/481aba636998127bf1b06f1f70534c08"},"breadcrumb":{"@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/#primaryimage","url":"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2023\/11\/Festival-Banner.png","contentUrl":"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2023\/11\/Festival-Banner.png","width":800,"height":451},{"@type":"BreadcrumbList","@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/tres-grupos-vascos-en-la-iscm-de-sudafrica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musikabulegoa.eus\/hub\/fr\/hub\/"},{"@type":"ListItem","position":2,"name":"Tres grupos vascos en la ISCM de Sud\u00e1frica"}]},{"@type":"WebSite","@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/#website","url":"https:\/\/musikabulegoa.eus\/hub\/fr\/","name":"Musika Bulegoa","description":"La Oficina de la M\u00fasica de Euskal Herria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musikabulegoa.eus\/hub\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/#\/schema\/person\/481aba636998127bf1b06f1f70534c08","name":"nu","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/35c862e58dd566edb3ea4c54e317aeec?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35c862e58dd566edb3ea4c54e317aeec?s=96&d=blank&r=g","caption":"nu"},"url":"https:\/\/musikabulegoa.eus\/hub\/fr\/author\/pedrositio-nu\/"}]}},"_links":{"self":[{"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/posts\/101736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/comments?post=101736"}],"version-history":[{"count":2,"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/posts\/101736\/revisions"}],"predecessor-version":[{"id":102018,"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/posts\/101736\/revisions\/102018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/media\/101737"}],"wp:attachment":[{"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/media?parent=101736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/categories?post=101736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/tags?post=101736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}