{"id":104282,"date":"2024-12-03T14:32:39","date_gmt":"2024-12-03T13:32:39","guid":{"rendered":"https:\/\/musikabulegoa.eus\/hub\/?p=104282"},"modified":"2024-12-03T14:32:39","modified_gmt":"2024-12-03T13:32:39","slug":"basque-music-en-esns-2025-ezezez","status":"publish","type":"post","link":"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/","title":{"rendered":"BASQUE. MUSIC. en ESNS 2025: EZEZEZ"},"content":{"rendered":"<p>EZEZEZ participar\u00e1 en el festival\u00a0<a href=\"https:\/\/esns.nl\/en\/\">ESNS<\/a> de la mano de BASQUE. MUSIC. La edici\u00f3n de 2025 tendr\u00e1 lugar entre el 15 y el 18 de enero en Groningen (Pa\u00edses Bajos), donde el grupo de Bilbao ofrecer\u00e1 un showcase el viernes d\u00eda 16 a las 19:50.<\/p>\n<p>ESNS es uno de los festivales de m\u00fasica m\u00e1s importantes de Europa y uno de los principales puntos de encuentro de profesionales de la m\u00fasica internacional. Adem\u00e1s de proteger el talento de cada pa\u00eds, impulsa nuevos proyectos musicales. Cada a\u00f1o se re\u00fanen en el recinto 4.000 delegados internacionales y m\u00e1s de 400 festivales de m\u00fasica.<\/p>\n<p><strong>EZEZEZ<\/strong><\/p>\n<p><a href=\"https:\/\/basquemusic.eus\/artists\/ezezez\/ar-95\/\">EZEZEZ<\/a> es una banda formada por Unai Madariaga, Eneko Ajangiz, \u00c1lvaro Olaetxea y Mikel Irigoyen, en la que la m\u00fasica tiene el mismo peso que el resto de aspectos que rodean a la banda. La militancia en el \u00abdo it yourself\u00bb y una creatividad desbordante hacen que compongan, escriban, toquen, graben, mezclen y mastericen todos sus temas la propia banda. Tambi\u00e9n los gr\u00e1ficos, los v\u00eddeos y el estilismo. EZEZEZ hacen ellos mismos todo lo relacionado con la banda con el objetivo de definir un sonido y una imagen \u00fanicos y contundentes. Y lo consiguen. Siendo una de las bandas m\u00e1s interesantes del panorama musical actual, sus potentes directos les han llevado a tocar en festivales como BIME Bilbao, Bilbao BBK Live, Monkey Week, Azkena Rock, Sonorama y muchos m\u00e1s.<\/p>\n<p>EZEZEZ lanz\u00f3 \u00abpuntofinal\u00bb a finales de noviembre de 2024, el primer single de su tercer \u00e1lbum. \u00abpuntofinal\u00bb es una explosi\u00f3n de energ\u00eda punk pero con alma funk (es super dancy) que se desliza como una katana en manos de un ninja: sutil, elegante y contundente. Narrado en su propio eusko\u00f1ol (una mezcla entre castellano y euskera) y cargado de iron\u00eda y poes\u00eda, \u00abpuntofinal\u00bb es una reflexi\u00f3n sobre la identidad y la aceptaci\u00f3n, explorando c\u00f3mo recibir amor puede ayudarnos a encontrar y validar el lugar que ocupamos en el mundo.<\/p>\n<p>BASQUE.MUSIC. en ESNS<\/p>\n<p>En ediciones anteriores Merina Gris, Zetak y Divorce From New York han sido las propuestas vascas seleccionadas para participar en este festival.<\/p>\n<p><iframe  id=\"_ytid_16191\"  width=\"800\" height=\"450\"  data-origwidth=\"800\" data-origheight=\"450\" src=\"https:\/\/www.youtube.com\/embed\/vIaBF0xKoyw?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;modestbranding=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EZEZEZ participar\u00e1 en el festival\u00a0ESNS de la mano de BASQUE. MUSIC. La edici\u00f3n de 2025 tendr\u00e1 lugar entre el 15 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":104284,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[501],"tags":[],"class_list":["post-104282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mb-internacionalizacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BASQUE. MUSIC. en ESNS 2025: EZEZEZ - Musika Bulegoa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BASQUE. MUSIC. en ESNS 2025: EZEZEZ - Musika Bulegoa\" \/>\n<meta property=\"og:description\" content=\"EZEZEZ participar\u00e1 en el festival\u00a0ESNS de la mano de BASQUE. MUSIC. La edici\u00f3n de 2025 tendr\u00e1 lugar entre el 15 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/\" \/>\n<meta property=\"og:site_name\" content=\"Musika Bulegoa\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-03T13:32:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2024\/12\/Ezezez_58-horizontal-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MusikaBulegoa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"MusikaBulegoa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/\",\"url\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/\",\"name\":\"BASQUE. MUSIC. en ESNS 2025: EZEZEZ - Musika Bulegoa\",\"isPartOf\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2024\/12\/Ezezez_58-horizontal-scaled.jpg\",\"datePublished\":\"2024-12-03T13:32:39+00:00\",\"dateModified\":\"2024-12-03T13:32:39+00:00\",\"author\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/#\/schema\/person\/62018fc25a2175efcf1a75cb8eac0b0f\"},\"breadcrumb\":{\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/#primaryimage\",\"url\":\"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2024\/12\/Ezezez_58-horizontal-scaled.jpg\",\"contentUrl\":\"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2024\/12\/Ezezez_58-horizontal-scaled.jpg\",\"width\":2560,\"height\":1710},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/hub\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BASQUE. MUSIC. en ESNS 2025: EZEZEZ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/#website\",\"url\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/\",\"name\":\"Musika Bulegoa\",\"description\":\"La Oficina de la M\u00fasica de Euskal Herria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/#\/schema\/person\/62018fc25a2175efcf1a75cb8eac0b0f\",\"name\":\"MusikaBulegoa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/127e5bff70608c38f998a3db1a101158?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/127e5bff70608c38f998a3db1a101158?s=96&d=blank&r=g\",\"caption\":\"MusikaBulegoa\"},\"url\":\"https:\/\/musikabulegoa.eus\/hub\/fr\/author\/musikabulegoa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BASQUE. MUSIC. en ESNS 2025: EZEZEZ - Musika Bulegoa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/","og_locale":"fr_FR","og_type":"article","og_title":"BASQUE. MUSIC. en ESNS 2025: EZEZEZ - Musika Bulegoa","og_description":"EZEZEZ participar\u00e1 en el festival\u00a0ESNS de la mano de BASQUE. MUSIC. La edici\u00f3n de 2025 tendr\u00e1 lugar entre el 15 [&hellip;]","og_url":"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/","og_site_name":"Musika Bulegoa","article_published_time":"2024-12-03T13:32:39+00:00","og_image":[{"width":2560,"height":1710,"url":"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2024\/12\/Ezezez_58-horizontal-scaled.jpg","type":"image\/jpeg"}],"author":"MusikaBulegoa","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"MusikaBulegoa","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/","url":"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/","name":"BASQUE. MUSIC. en ESNS 2025: EZEZEZ - Musika Bulegoa","isPartOf":{"@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/#primaryimage"},"image":{"@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/#primaryimage"},"thumbnailUrl":"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2024\/12\/Ezezez_58-horizontal-scaled.jpg","datePublished":"2024-12-03T13:32:39+00:00","dateModified":"2024-12-03T13:32:39+00:00","author":{"@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/#\/schema\/person\/62018fc25a2175efcf1a75cb8eac0b0f"},"breadcrumb":{"@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/#primaryimage","url":"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2024\/12\/Ezezez_58-horizontal-scaled.jpg","contentUrl":"https:\/\/musikabulegoa.eus\/hub\/wp-content\/uploads\/2024\/12\/Ezezez_58-horizontal-scaled.jpg","width":2560,"height":1710},{"@type":"BreadcrumbList","@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/basque-music-en-esns-2025-ezezez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/musikabulegoa.eus\/hub\/fr\/hub\/"},{"@type":"ListItem","position":2,"name":"BASQUE. MUSIC. en ESNS 2025: EZEZEZ"}]},{"@type":"WebSite","@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/#website","url":"https:\/\/musikabulegoa.eus\/hub\/fr\/","name":"Musika Bulegoa","description":"La Oficina de la M\u00fasica de Euskal Herria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musikabulegoa.eus\/hub\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/#\/schema\/person\/62018fc25a2175efcf1a75cb8eac0b0f","name":"MusikaBulegoa","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/musikabulegoa.eus\/hub\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/127e5bff70608c38f998a3db1a101158?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/127e5bff70608c38f998a3db1a101158?s=96&d=blank&r=g","caption":"MusikaBulegoa"},"url":"https:\/\/musikabulegoa.eus\/hub\/fr\/author\/musikabulegoa\/"}]}},"_links":{"self":[{"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/posts\/104282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/comments?post=104282"}],"version-history":[{"count":1,"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/posts\/104282\/revisions"}],"predecessor-version":[{"id":104283,"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/posts\/104282\/revisions\/104283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/media\/104284"}],"wp:attachment":[{"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/media?parent=104282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/categories?post=104282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/musikabulegoa.eus\/hub\/fr\/wp-json\/wp\/v2\/tags?post=104282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}